{"id":6872,"date":"2023-12-01T09:08:54","date_gmt":"2023-12-01T08:08:54","guid":{"rendered":"https:\/\/panoff.ch\/faq\/"},"modified":"2024-04-24T10:43:54","modified_gmt":"2024-04-24T08:43:54","slug":"faq","status":"publish","type":"page","link":"https:\/\/panoff.ch\/de\/faq\/","title":{"rendered":"FAQ"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6872\" class=\"elementor elementor-6872\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b9f8e1a elementor-section-full_width elementor-section-height-min-height elementor-section-items-bottom max-width-2k elementor-section-height-default qodef-elementor-content-no\" data-id=\"b9f8e1a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dc7ab01\" data-id=\"dc7ab01\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-02e8a0c animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"02e8a0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1 class=\"page-title\">FAQ<\/h1>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c759ea elementor-widget__width-initial animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"8c759ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"color: #fff;\">Erfahre mehr \u00fcber unseren Bewerbungsprozess, die Art und Weise, wie wir arbeiten und welche Karrierem\u00f6glichkeiten Panoff Consulting bietet.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fdd29ae elementor-section-full_width qodef-elementor-content-grid elementor-section-height-default elementor-section-height-default\" data-id=\"fdd29ae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b64614\" data-id=\"4b64614\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4baaab faq-accordion elementor-widget elementor-widget-accordion\" data-id=\"a4baaab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1721\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1721\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Wie kann ich mich bei Panoff Consulting bewerben?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1721\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1721\"><p data-pm-slice=\"1 1 []\">Bitte benutze das <a href=\"\/de\/offene-stellen\/\"><span style=\"color: #5a8bab;\">Bewerbungsformular<\/span><\/a>, um Deine Bewerbung einzureichen. Sobald wir ein umfassendes Bild von Dir und Deiner Pers\u00f6nlichkeit gewonnen haben, m\u00f6chten wir Dich gerne in einem ersten Interview besser kennenlernen. Wenn Du Fragen vor der Bewerbung hast, kontaktiere bitte <a href=\"mailto:konstantin.zirkelbach@panoff.ch\"><span style=\"color: #5a8bab;\">Konstantin Zirkelbach<\/span><\/a>.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1722\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1722\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Welche Dokumente ben\u00f6tige ich f\u00fcr meine Bewerbung?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1722\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1722\">Damit wir uns ein umfassendes Bild von Dir machen k\u00f6nnen, lasse uns gerne ein Anschreiben, Deinen Lebenslauf sowie alle relevanten Zertifikate und Zeugnisse zukommen. Aber keine Sorge, wir sind viel mehr an Dir und deiner Person, als den harten Fakten interessiert.<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1723\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1723\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Wie lange dauert es, bis ich mit einer R\u00fcckmeldung rechnen kann?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1723\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1723\">Wir werden einige Tage ben\u00f6tigen, um alles gr\u00fcndlich zu pr\u00fcfen. Du kannst sicher sein, dass wir uns zeitnah wieder bei Dir melden werden. Falls Du in der Zwischenzeit Fragen hast oder weitere Informationen ben\u00f6tigst, z\u00f6gere nicht, uns jederzeit zu kontaktieren.<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1724\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1724\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Wie l\u00e4uft der Bewerbungsprozess ab?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1724\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1724\"><p>Nachdem wir Deine Bewerbungsunterlagen erhalten und uns ein umfassendes Bild von Dir und Deiner Person gemacht haben, w\u00fcrden wir Dich gerne bei einem ersten Online-Termin n\u00e4her kennenlernen. F\u00e4llt dieses Gespr\u00e4ch von beiden Seiten positiv aus, laden wir Dich daraufhin zu einem pers\u00f6nlichen Bewerbungsgespr\u00e4ch inkl. Case Study ein. Haben wir Dich und Du uns \u00fcberzeugt, steht Deinem Start bei Panoff Consulting nichts mehr im Wege.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1725\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1725\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Wie sieht ein typischer Arbeitsalltag bei Euch aus?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1725\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1725\"><p>Auch, wenn wir stetig wachsen, sind wir noch ein kleines und famili\u00e4res Team. Somit packt jedes Teammitglied nicht nur bei Projektthemen mit an, sondern \u00fcbernimmt auch Verantwortung f\u00fcr interne Themen und deren Weiterentwicklung. So kann ein typischer Arbeitstag beinhalten, dass Du zwischen Projektterminen vor Kunde, internen Abstimmungsterminen und der Bearbeitung von Themen, die uns als Unternehmen weiterentwickeln das richtige Gleichgewicht finden musst. Das erfordert ein hohes Mass an Eigenverantwortung, was bei uns grunds\u00e4tzlich gefordert, aber auch aktiv gef\u00f6rdert wird.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1726\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1726\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Worin bestehen eure Projekte?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1726\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1726\">Unsere Projekte reichen von Benchmarkanalysen \u00fcber Strategieentwicklung und Konzeption bis zur Umsetzungsbegleitung. Wir verstehen uns dabei als Fachexperten der Automobilbranche und ersten Ansprechpartner f\u00fcr unsere Kunden in allen Themen rund um die Optimierung und Digitalisierung von Prozessen im Automotive Retail und insbesondere den zugeh\u00f6rigen Systemen, die dort zum Einsatz kommen. Dabei fungieren wir oft als Schnittstelle zwischen den Fachbereichen des Kunden und internen oder externen Entwicklungseinheiten.<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1727\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-1727\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Welche Arbeitsform gibt es bei Panoff Consulting?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1727\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-1727\"><p>Wir arbeiten \u00fcberwiegend aus dem Home Office. Trotzdem gibt es regelm\u00e4ssige Treffen in verschiedenen europ\u00e4ischen St\u00e4dten, um das Miteinander und die pers\u00f6nliche Zusammenarbeit im Team zu f\u00f6rdern. <br \/>Die Projekte mit Kunden werden haupts\u00e4chlich remote durchgef\u00fchrt, wobei gelegentlich Termine mit Kunden vor Ort stattfinden k\u00f6nnen.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1728\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-1728\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Inwiefern werden Weiterbildungsm\u00f6glichkeiten angeboten?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1728\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-1728\"><p>Wir m\u00f6chten Dich bei Deiner pers\u00f6nlichen und beruflichen Weiterentwicklung bestm\u00f6glich unterst\u00fctzen. Deshalb bieten wir Dir ein individuell, auf Dich abgestimmten Fortbildungsplan an inkl. einem gro\u00dfz\u00fcgigen j\u00e4hrlichen Weiterbildungsbudget.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1729\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-1729\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Warum sollte ich bei Panoff Consulting arbeiten?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1729\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-1729\"><p>Panoff Consulting bietet Dir ein r\u00fccksichtsvolles, wertsch\u00e4tzendes und sich gegenseitig unterst\u00fctzendes Umfeld, bei dem Du Gestaltungsfreiheit hast und dich somit pers\u00f6nlich weiterentwickeln kannst, sowie einige zus\u00e4tzliche Benefits:<\/p><p>\u00a0<\/p><ul><li>Hohes Mass an Gestaltungs- und Entwicklungsfreiheit in einem Umfeld mit hohem pers\u00f6nlichen Entwicklungspotential &amp; Angebot eines individuell abgestimmten Fortbildungsplans sowie Budgets<\/li><li>Begleitung durch einen Senior Consultant, der Dich bei Deiner Entwicklung unterst\u00fctzt<\/li><li>Freie Standortwahl innerhalb Deutschlands<\/li><li>Monatliche Treffen in europ\u00e4ischen St\u00e4dten und j\u00e4hrliche Sommer- und Winterevents<\/li><li>Ein r\u00fccksichtsvolles, wertsch\u00e4tzendes und sich gegenseitig unterst\u00fctzendes Umfeld<\/li><li>Wir beteiligen alle Mitarbeiter*innen finanziell am Erfolg des Unternehmensergebnisses<\/li><li>Durch den Arbeitgeber bezuschusste betriebliche Altersvorsorge (BAV)<\/li><li>Ausstellung einer DB Bahncard 50 (berufliche &amp; private Nutzung)<\/li><li>uvm.<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-943e005 elementor-section-full_width qodef-elementor-content-grid elementor-section-height-default elementor-section-height-default\" data-id=\"943e005\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-40732d5\" data-id=\"40732d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c6489f elementor-widget elementor-widget-text-editor\" data-id=\"2c6489f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Offene Stellen<\/h1>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ac7406 open-pos-btn elementor-widget elementor-widget-qi_addons_for_elementor_button\" data-id=\"8ac7406\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a class=\"qodef-shortcode qodef-m qodef-qi-button qodef-html--link qodef-layout--filled qodef-type--standard qodef-size--full qodef-icon--right qodef-hover--icon-move-horizontal-short\" href=\"\/de\/offene-stellen\/consultant-m-w-d-automotive-retail\/\" target=\"_self\">\n\t<span class=\"qodef-m-text\">Consultant (m\/w\/d) - Automotive Retail<\/span>\n\t\t<span class=\"qodef-m-icon\">\n\t\t<span class=\"qodef-m-icon-inner\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"31\" height=\"23\" viewBox=\"0 0 31 23\"><g fill=\"#5A8BAB\" fill-rule=\"nonzero\"><path d=\"M19.08 22.83a1 1 0 0 1-.7-.29 1 1 0 0 1 0-1.41l9.29-9.3-9.29-9.29a1 1 0 0 1 1.41-1.41l10 10a1 1 0 0 1 0 1.41l-10 10a1 1 0 0 1-.71.29z\"><\/path><path d=\"M29 13H1a1 1 0 0 1 0-2h28a1 1 0 0 1 0 2z\"><\/path><\/g><\/svg>\t\t\t\t\t<\/span>\n\t<\/span>\n<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98adecd open-pos-btn elementor-widget elementor-widget-qi_addons_for_elementor_button\" data-id=\"98adecd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a class=\"qodef-shortcode qodef-m qodef-qi-button qodef-html--link qodef-layout--filled qodef-type--standard qodef-size--full qodef-icon--right qodef-hover--icon-move-horizontal-short\" href=\"\/de\/offene-stellen\/senior-consultant-m-w-d-automotive-retail\/\" target=\"_self\">\n\t<span class=\"qodef-m-text\">Senior Consultant (m\/w\/d) \u2013 Automotive Retail<\/span>\n\t\t<span class=\"qodef-m-icon\">\n\t\t<span class=\"qodef-m-icon-inner\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"31\" height=\"23\" viewBox=\"0 0 31 23\"><g fill=\"#5A8BAB\" fill-rule=\"nonzero\"><path d=\"M19.08 22.83a1 1 0 0 1-.7-.29 1 1 0 0 1 0-1.41l9.29-9.3-9.29-9.29a1 1 0 0 1 1.41-1.41l10 10a1 1 0 0 1 0 1.41l-10 10a1 1 0 0 1-.71.29z\"><\/path><path d=\"M29 13H1a1 1 0 0 1 0-2h28a1 1 0 0 1 0 2z\"><\/path><\/g><\/svg>\t\t\t\t\t<\/span>\n\t<\/span>\n<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e59bb42 open-pos-btn elementor-widget elementor-widget-qi_addons_for_elementor_button\" data-id=\"e59bb42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a class=\"qodef-shortcode qodef-m qodef-qi-button qodef-html--link qodef-layout--filled qodef-type--standard qodef-size--full qodef-icon--right qodef-hover--icon-move-horizontal-short\" href=\"\/de\/offene-stellen\/initiativbewerbung-m-w-d-automotive-retail\/\" target=\"_self\">\n\t<span class=\"qodef-m-text\">Initiativbewerbung (m\/w\/d) \u2013 Automotive Retail<\/span>\n\t\t<span class=\"qodef-m-icon\">\n\t\t<span class=\"qodef-m-icon-inner\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"31\" height=\"23\" viewBox=\"0 0 31 23\"><g fill=\"#5A8BAB\" fill-rule=\"nonzero\"><path d=\"M19.08 22.83a1 1 0 0 1-.7-.29 1 1 0 0 1 0-1.41l9.29-9.3-9.29-9.29a1 1 0 0 1 1.41-1.41l10 10a1 1 0 0 1 0 1.41l-10 10a1 1 0 0 1-.71.29z\"><\/path><path d=\"M29 13H1a1 1 0 0 1 0-2h28a1 1 0 0 1 0 2z\"><\/path><\/g><\/svg>\t\t\t\t\t<\/span>\n\t<\/span>\n<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-564bc6a open-pos-section elementor-widget elementor-widget-qi_addons_for_elementor_button\" data-id=\"564bc6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a class=\"qodef-shortcode qodef-m qodef-qi-button qodef-html--link qodef-layout--filled qodef-type--standard qodef-icon--right qodef-hover--icon-move-horizontal-short\" href=\"\/open-positions\/\" target=\"_self\">\n\t<span class=\"qodef-m-text\">Alle anzeigen<\/span>\n\t\t<span class=\"qodef-m-icon\">\n\t\t<span class=\"qodef-m-icon-inner\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"14\" height=\"13\" viewBox=\"0 0 14 13\"><path d=\"m2.977 1.26 8.786.062L0 12.046l.9.892L12.664 2.212l.063 8.287 1.273.035L13.999 0H2.94z\" fill=\"#FFF\" fill-rule=\"nonzero\"><\/path><\/svg>\t\t\t\t\t<\/span>\n\t<\/span>\n<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>FAQ Erfahre mehr \u00fcber unseren Bewerbungsprozess, die Art und Weise, wie wir arbeiten und welche Karrierem\u00f6glichkeiten Panoff Consulting bietet. Wie kann ich mich bei Panoff Consulting bewerben? Bitte benutze das Bewerbungsformular, um Deine Bewerbung einzureichen. Sobald wir ein umfassendes Bild von Dir und Deiner Pers\u00f6nlichkeit gewonnen haben, m\u00f6chten wir Dich gerne in einem ersten Interview [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6690,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"content-type":"","footnotes":""},"class_list":["post-6872","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Panoff Consulting - Wir bringen Menschen mit Freude in Bewegung<\/title>\n<meta name=\"description\" content=\"Entdecken Sie die M\u00f6glichkeiten bei Panoff Consulting mit unseren FAQ. Erfahren Sie, wie Sie sich bewerben k\u00f6nnen, welche Unterlagen erforderlich sind, und entdecken Sie den typischen Arbeitstag, die Projekte und die verf\u00fcgbaren Arbeitsformate. Informieren Sie sich \u00fcber unser Engagement f\u00fcr kontinuierliche Weiterbildung und warum es sich lohnt, bei Panoff Consulting zu arbeiten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/panoff.ch\/de\/faq\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Panoff Consulting - Wir bringen Menschen mit Freude in Bewegung\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie die M\u00f6glichkeiten bei Panoff Consulting mit unseren FAQ. Erfahren Sie, wie Sie sich bewerben k\u00f6nnen, welche Unterlagen erforderlich sind, und entdecken Sie den typischen Arbeitstag, die Projekte und die verf\u00fcgbaren Arbeitsformate. Informieren Sie sich \u00fcber unser Engagement f\u00fcr kontinuierliche Weiterbildung und warum es sich lohnt, bei Panoff Consulting zu arbeiten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/panoff.ch\/de\/faq\/\" \/>\n<meta property=\"og:site_name\" content=\"Panoff Consulting\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-24T08:43:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/panoff.ch\/wp-content\/uploads\/2023\/12\/social-share-img10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/panoff.ch\\\/de\\\/faq\\\/\",\"url\":\"https:\\\/\\\/panoff.ch\\\/de\\\/faq\\\/\",\"name\":\"Panoff Consulting - Wir bringen Menschen mit Freude in Bewegung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/panoff.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/panoff.ch\\\/de\\\/faq\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/panoff.ch\\\/de\\\/faq\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/panoff.ch\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/social-share-img10.jpg\",\"datePublished\":\"2023-12-01T08:08:54+00:00\",\"dateModified\":\"2024-04-24T08:43:54+00:00\",\"description\":\"Entdecken Sie die M\u00f6glichkeiten bei Panoff Consulting mit unseren FAQ. Erfahren Sie, wie Sie sich bewerben k\u00f6nnen, welche Unterlagen erforderlich sind, und entdecken Sie den typischen Arbeitstag, die Projekte und die verf\u00fcgbaren Arbeitsformate. Informieren Sie sich \u00fcber unser Engagement f\u00fcr kontinuierliche Weiterbildung und warum es sich lohnt, bei Panoff Consulting zu arbeiten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/panoff.ch\\\/de\\\/faq\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/panoff.ch\\\/de\\\/faq\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/panoff.ch\\\/de\\\/faq\\\/#primaryimage\",\"url\":\"https:\\\/\\\/panoff.ch\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/social-share-img10.jpg\",\"contentUrl\":\"https:\\\/\\\/panoff.ch\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/social-share-img10.jpg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/panoff.ch\\\/de\\\/faq\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/panoff.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAQ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/panoff.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/panoff.ch\\\/de\\\/\",\"name\":\"Panoff Consulting\",\"description\":\"Wir bringen Menschen mit Freude in Bewegung\",\"publisher\":{\"@id\":\"https:\\\/\\\/panoff.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/panoff.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/panoff.ch\\\/de\\\/#organization\",\"name\":\"Panoff Consulting\",\"url\":\"https:\\\/\\\/panoff.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/panoff.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/panoff.ch\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/panoff-logo.svg\",\"contentUrl\":\"https:\\\/\\\/panoff.ch\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/panoff-logo.svg\",\"width\":565,\"height\":168,\"caption\":\"Panoff Consulting\"},\"image\":{\"@id\":\"https:\\\/\\\/panoff.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Panoff Consulting - Wir bringen Menschen mit Freude in Bewegung","description":"Entdecken Sie die M\u00f6glichkeiten bei Panoff Consulting mit unseren FAQ. Erfahren Sie, wie Sie sich bewerben k\u00f6nnen, welche Unterlagen erforderlich sind, und entdecken Sie den typischen Arbeitstag, die Projekte und die verf\u00fcgbaren Arbeitsformate. Informieren Sie sich \u00fcber unser Engagement f\u00fcr kontinuierliche Weiterbildung und warum es sich lohnt, bei Panoff Consulting zu arbeiten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/panoff.ch\/de\/faq\/","og_locale":"de_DE","og_type":"article","og_title":"Panoff Consulting - Wir bringen Menschen mit Freude in Bewegung","og_description":"Entdecken Sie die M\u00f6glichkeiten bei Panoff Consulting mit unseren FAQ. Erfahren Sie, wie Sie sich bewerben k\u00f6nnen, welche Unterlagen erforderlich sind, und entdecken Sie den typischen Arbeitstag, die Projekte und die verf\u00fcgbaren Arbeitsformate. Informieren Sie sich \u00fcber unser Engagement f\u00fcr kontinuierliche Weiterbildung und warum es sich lohnt, bei Panoff Consulting zu arbeiten.","og_url":"https:\/\/panoff.ch\/de\/faq\/","og_site_name":"Panoff Consulting","article_modified_time":"2024-04-24T08:43:54+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/panoff.ch\/wp-content\/uploads\/2023\/12\/social-share-img10.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/panoff.ch\/de\/faq\/","url":"https:\/\/panoff.ch\/de\/faq\/","name":"Panoff Consulting - Wir bringen Menschen mit Freude in Bewegung","isPartOf":{"@id":"https:\/\/panoff.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/panoff.ch\/de\/faq\/#primaryimage"},"image":{"@id":"https:\/\/panoff.ch\/de\/faq\/#primaryimage"},"thumbnailUrl":"https:\/\/panoff.ch\/wp-content\/uploads\/2023\/12\/social-share-img10.jpg","datePublished":"2023-12-01T08:08:54+00:00","dateModified":"2024-04-24T08:43:54+00:00","description":"Entdecken Sie die M\u00f6glichkeiten bei Panoff Consulting mit unseren FAQ. Erfahren Sie, wie Sie sich bewerben k\u00f6nnen, welche Unterlagen erforderlich sind, und entdecken Sie den typischen Arbeitstag, die Projekte und die verf\u00fcgbaren Arbeitsformate. Informieren Sie sich \u00fcber unser Engagement f\u00fcr kontinuierliche Weiterbildung und warum es sich lohnt, bei Panoff Consulting zu arbeiten.","breadcrumb":{"@id":"https:\/\/panoff.ch\/de\/faq\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/panoff.ch\/de\/faq\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/panoff.ch\/de\/faq\/#primaryimage","url":"https:\/\/panoff.ch\/wp-content\/uploads\/2023\/12\/social-share-img10.jpg","contentUrl":"https:\/\/panoff.ch\/wp-content\/uploads\/2023\/12\/social-share-img10.jpg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/panoff.ch\/de\/faq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/panoff.ch\/de\/"},{"@type":"ListItem","position":2,"name":"FAQ"}]},{"@type":"WebSite","@id":"https:\/\/panoff.ch\/de\/#website","url":"https:\/\/panoff.ch\/de\/","name":"Panoff Consulting","description":"Wir bringen Menschen mit Freude in Bewegung","publisher":{"@id":"https:\/\/panoff.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/panoff.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/panoff.ch\/de\/#organization","name":"Panoff Consulting","url":"https:\/\/panoff.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/panoff.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/panoff.ch\/wp-content\/uploads\/2023\/11\/panoff-logo.svg","contentUrl":"https:\/\/panoff.ch\/wp-content\/uploads\/2023\/11\/panoff-logo.svg","width":565,"height":168,"caption":"Panoff Consulting"},"image":{"@id":"https:\/\/panoff.ch\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/panoff.ch\/de\/wp-json\/wp\/v2\/pages\/6872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/panoff.ch\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/panoff.ch\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/panoff.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/panoff.ch\/de\/wp-json\/wp\/v2\/comments?post=6872"}],"version-history":[{"count":0,"href":"https:\/\/panoff.ch\/de\/wp-json\/wp\/v2\/pages\/6872\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/panoff.ch\/de\/wp-json\/wp\/v2\/media\/6690"}],"wp:attachment":[{"href":"https:\/\/panoff.ch\/de\/wp-json\/wp\/v2\/media?parent=6872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}